{"id":135,"count":2,"description":"","link":"https:\/\/xio-online.com\/es\/tag\/xiaomi-mi-11i-es\/","name":"Xiaomi Mi 11i","slug":"xiaomi-mi-11i-es","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Xiaomi Mi 11i archivos - Xiaomi Latin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xio-online.com\/es\/tag\/xiaomi-mi-11i-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xiaomi Mi 11i archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xio-online.com\/es\/tag\/xiaomi-mi-11i-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Xiaomi Latin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/xio-online.com\\\/es\\\/tag\\\/xiaomi-mi-11i-es\\\/\",\"url\":\"https:\\\/\\\/xio-online.com\\\/es\\\/tag\\\/xiaomi-mi-11i-es\\\/\",\"name\":\"Xiaomi Mi 11i archivos - Xiaomi Latin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xio-online.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xio-online.com\\\/es\\\/tag\\\/xiaomi-mi-11i-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xio-online.com\\\/es\\\/tag\\\/xiaomi-mi-11i-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xio-online.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xiaomi Mi 11i\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xio-online.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xio-online.com\\\/es\\\/\",\"name\":\"Xiaomi Latin\",\"description\":\"Official partner Xiaomi \",\"publisher\":{\"@id\":\"https:\\\/\\\/xio-online.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xio-online.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xio-online.com\\\/es\\\/#organization\",\"name\":\"Xiaomi Venezuela\",\"url\":\"https:\\\/\\\/xio-online.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xio-online.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xio-online.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/xio-store-logo.png\",\"contentUrl\":\"https:\\\/\\\/xio-online.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/xio-store-logo.png\",\"width\":1797,\"height\":397,\"caption\":\"Xiaomi Venezuela\"},\"image\":{\"@id\":\"https:\\\/\\\/xio-online.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Xiaomi Mi 11i archivos - Xiaomi Latin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xio-online.com\/es\/tag\/xiaomi-mi-11i-es\/","og_locale":"es_ES","og_type":"article","og_title":"Xiaomi Mi 11i archivos","og_url":"https:\/\/xio-online.com\/es\/tag\/xiaomi-mi-11i-es\/","og_site_name":"Xiaomi Latin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/xio-online.com\/es\/tag\/xiaomi-mi-11i-es\/","url":"https:\/\/xio-online.com\/es\/tag\/xiaomi-mi-11i-es\/","name":"Xiaomi Mi 11i archivos - Xiaomi Latin","isPartOf":{"@id":"https:\/\/xio-online.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/xio-online.com\/es\/tag\/xiaomi-mi-11i-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/xio-online.com\/es\/tag\/xiaomi-mi-11i-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xio-online.com\/es\/"},{"@type":"ListItem","position":2,"name":"Xiaomi Mi 11i"}]},{"@type":"WebSite","@id":"https:\/\/xio-online.com\/es\/#website","url":"https:\/\/xio-online.com\/es\/","name":"Xiaomi Latin","description":"Official partner Xiaomi ","publisher":{"@id":"https:\/\/xio-online.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xio-online.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/xio-online.com\/es\/#organization","name":"Xiaomi Venezuela","url":"https:\/\/xio-online.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xio-online.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/xio-online.com\/wp-content\/uploads\/2020\/08\/xio-store-logo.png","contentUrl":"https:\/\/xio-online.com\/wp-content\/uploads\/2020\/08\/xio-store-logo.png","width":1797,"height":397,"caption":"Xiaomi Venezuela"},"image":{"@id":"https:\/\/xio-online.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/xio-online.com\/es\/wp-json\/wp\/v2\/tags\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xio-online.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/xio-online.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/xio-online.com\/es\/wp-json\/wp\/v2\/posts?tags=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}